{"id":1222,"date":"2016-02-12T14:47:05","date_gmt":"2016-02-12T14:47:05","guid":{"rendered":"https:\/\/www.maxorata.es\/?page_id=1222"},"modified":"2020-12-11T12:11:43","modified_gmt":"2020-12-11T12:11:43","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/maxorata.es\/en\/aviso-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1547816869114 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 20%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#716a4b;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#716a4b;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center;\"><span style=\"color: #716a4b;\">Aviso Legal y Pol\u00edtica de Privacidad<\/span><\/h1>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><span style=\"color: #000000;\"><strong>IDENTIFICACI\u00d3N<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, GRUPO GANADEROS DE FUERTEVENTURA S.L., le informa que los datos aqu\u00ed consignados corresponden a la entidad titular del sitio web.<\/span><br \/>\n<span style=\"color: #000000;\">Denominaci\u00f3n: GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/span><br \/>\n<span style=\"color: #000000;\">Domicilio: COCHINILLA URB. RISCO PRIETO, 29 &#8211; Nave PUERTO DEL ROSARIO 35600 (LAS PALMAS)<\/span><br \/>\n<span style=\"color: #000000;\">Tel\u00e9fono: 928531563<\/span><br \/>\n<span style=\"color: #000000;\">Email: atencionalcliente@maxorata.es<\/span><br \/>\n<span style=\"color: #000000;\">CIF: B35077478<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>PROPIEDAD INTELECTUAL E INDUSTRIAL<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Todos los derechos de Propiedad Industrial e Intelectual de la totalidad de elementos contenidos en esta Web, incluidas las marcas comerciales, formatos, dise\u00f1os gr\u00e1ficos, textos, im\u00e1genes y documentos, pertenecen a y se encuentran protegidos por las leyes espa\u00f1olas e internacionales sobre propiedad Intelectual e Industrial. Queda expresamente prohibida la<\/span><br \/>\n<span style=\"color: #000000;\">reproducci\u00f3n total o parcial de este sitio Web y de cualquiera de sus contenidos sin el permiso expreso y por escrito de <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">El acceso al sitio web no implica ning\u00fan tipo de renuncia, transmisi\u00f3n, licencia o cesi\u00f3n de dichos derechos por parte de <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>, salvo que se establezca expresamente lo contrario.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>CONDICIONES DE USO<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">El acceso a este sitio Web implica la aceptaci\u00f3n de estas condiciones de uso sin reservas que regulan el acceso y la utilizaci\u00f3n del mismo con el fin de poner a disposici\u00f3n de los usuarios informaci\u00f3n sobre nuestros productos.<\/span><br \/>\n<span style=\"color: #000000;\">Se proh\u00edbe expresamente la utilizaci\u00f3n de los contenidos de este sitio Web para su utilizaci\u00f3n con fines comerciales o para su distribuci\u00f3n, transformaci\u00f3n o comunicaci\u00f3n.<\/span><br \/>\n<span style=\"color: #000000;\"><strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>, no responder\u00e1 de ninguna consecuencia, da\u00f1o o perjuicio que pudieran derivarse de dicha utilizaci\u00f3n o uso de la informaci\u00f3n.<\/span><br \/>\n<span style=\"color: #000000;\">Tanto el acceso a esta Web como el uso que pueda hacerse de la informaci\u00f3n contenida en la misma es de la exclusiva responsabilidad de quien lo realiza.<\/span><br \/>\n<span style=\"color: #000000;\">El usuario se obliga a no utilizar la informaci\u00f3n que se publica en esta Web con fines o efectos il\u00edcitos o lesivos, a no da\u00f1ar o inutilizar la informaci\u00f3n y a no realizar cualquier otra acci\u00f3n que puedan ser contraria al contenido de este Aviso Legal.<\/span><br \/>\n<span style=\"color: #000000;\"><strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong> no puede asegurar la inexistencia de interrupciones o errores en el acceso a este sitio Web, aunque pondr\u00e1 sus mayores<\/span><br \/>\n<span style=\"color: #000000;\">esfuerzos para evitarlos.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>POL\u00cdTICA DE PROTECCI\u00d3N DE DATOS<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">En cumplimiento del REGLAMENTO (UE) 2016\/679 DEL PARLAMENTO EUROPEO Y DEL CONSEJO de 27 de Abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos y su normativa de desarrollo, se le informa que los datos personales proporcionados por usted<\/span><br \/>\n<span style=\"color: #000000;\">ser\u00e1n tratados con las siguientes finalidades:<\/span><br \/>\n<span style=\"color: #000000;\">&#8211; Informarle acerca de nuestros productos y servicios, cuando as\u00ed lo solicite.<\/span><br \/>\n<span style=\"color: #000000;\">&#8211; Dar contestaci\u00f3n y gestionar sus consultas, comentarios y sugerencias, en su caso.<\/span><br \/>\n<span style=\"color: #000000;\">&#8211; Gestionar su participaci\u00f3n en presentes y futuros procesos de selecci\u00f3n, cuando nos haga llegar sus datos (inclu\u00eddo su curr\u00edculo) con dicha finalidad. Cuando iniciemos alg\u00fan proceso de selecci\u00f3n donde pueda encajar su perfil, nos pondremos en contacto con usted. Mantendremos sus datos personales durante un periodo de dos a\u00f1os con el fin de poder contar con su participaci\u00f3n en futuros procesos.<\/span><br \/>\n<span style=\"color: #000000;\">A trav\u00e9s de la cumplimentaci\u00f3n de formularios de contacto de la Web o mediante el env\u00edo de correos electr\u00f3nicos o cualquier otro tipo de solicitud de informaci\u00f3n remitida a <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>, el interesado presta su consentimiento expreso para el tratamiento de sus datos personales.<\/span><br \/>\n<span style=\"color: #000000;\">En ning\u00fan caso\u00a0<strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>, utilizar\u00e1 los datos personales de los interesados para fines distintos de los anteriormente mencionados, ni<\/span><br \/>\n<span style=\"color: #000000;\">los comunicar\u00e1 a terceros sin el consentimiento previo y expreso del afectado, y se compromete a guardar el debido secreto profesional y a establecer las medidas t\u00e9cnicas y organizativas necesarias para salvaguardar la informaci\u00f3n conforme a los requerimientos que establece el mencionado Reglamento.<\/span><br \/>\n<span style=\"color: #000000;\">Sus datos personales se conservar\u00e1n en nuestros registros durante un periodo de tres a\u00f1os. No obstante, en cualquier momento usted puede solicitar el acceso a sus datos personales y su rectificaci\u00f3n o supresi\u00f3n. As\u00ed como, limitar su tratamiento, o directamente oponerse al tratamiento o ejercer el derecho a la portabilidad de los mismos.<\/span><br \/>\n<span style=\"color: #000000;\">Tambi\u00e9n le informamos de su derecho a presentar una reclamaci\u00f3n ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, si considera que en el tratamiento de sus datos no se est\u00e1n respetando sus derechos.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>POL\u00cdTICA DE PROTECCI\u00d3N DE MENORES<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Quien facilita los datos a trav\u00e9s de los formularios de esta Web y acepta su tratamiento declara formalmente ser mayor de 13 a\u00f1os.<\/span><br \/>\n<span style=\"color: #000000;\">Queda prohibido el acceso y uso del portal a los menores de 13 a\u00f1os de edad.<\/span><br \/>\n<span style=\"color: #000000;\">recuerda a las personas mayores de edad que tengan a su cargo menores, que ser\u00e1 de su exclusiva responsabilidad si alg\u00fan menor incorpora sus datos para solicitar alg\u00fan producto.<\/span><br \/>\n<span style=\"color: #000000;\">Tambi\u00e9n les informa que existen programas inform\u00e1ticos para acotar la navegaci\u00f3n mediante el filtro o bloqueo a determinados contenidos.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>REDES SOCIALES<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Al seguir nuestro perfil en las redes sociales consiente expresamente el tratamiento de sus datos personales conforme a su pol\u00edtica de privacidad. Tambi\u00e9n consiente expresamente el acceso de al tratamiento de sus datos contenidos en la lista de amigos y a que a que las noticias publicadas sobre cualquier producto de aparezcan en su muro.<\/span><br \/>\n<span style=\"color: #000000;\">De conformidad con el REGLAMENTO (UE) 2016\/679 DEL PARLAMENTO EUROPEO, le informamos que los datos personales de los seguidores de <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>, ser\u00e1n incorporados a un fichero cuyo titular es con la finalidad de mantenerle informados a trav\u00e9s de las redes sociales sobre noticias relativas a las actividades de <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>.<\/span><br \/>\n<span style=\"color: #000000;\">Su petici\u00f3n para conectar, implica necesariamente su consentimiento para los tratamientos se\u00f1alados.<\/span><br \/>\n<span style=\"color: #000000;\">La publicaci\u00f3n de comentarios y contenidos en las redes sociales se convertir\u00e1n en informaci\u00f3n p\u00fablica, por lo que los usuarios deber\u00e1n tener especial cautela cuando decidan compartir su informaci\u00f3n personal. <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong> no se hace responsable por la informaci\u00f3n que los usuarios incorporen en la p\u00e1gina. No obstante, las personas cuyos datos personales se encuentren publicados o est\u00e9n incluidos en comentarios, podr\u00e1n solicitar a la cancelaci\u00f3n de los mismos.<\/span><br \/>\n<span style=\"color: #000000;\">En cualquier momento, usted puede ejercer los derechos de acceso, rectificaci\u00f3n, supresi\u00f3n y oposici\u00f3n, limitar el tratamiento de sus datos, o directamente oponerse al tratamiento, o ejercer el derecho a la portabilidad de los mismos.<\/span><br \/>\n<span style=\"color: #000000;\">Todo ello, mediante escrito, acompa\u00f1ado de copia de documento oficial que le identifique, dirigido a <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>. En caso de disconformidad con el tratamiento, tambi\u00e9n tiene derecho a presentar una reclamaci\u00f3n ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>ENLACES A OTRAS WEBS<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">Los enlaces (links) que puede encontrar en esta Web son un servicio a los usuarios. Estas p\u00e1ginas no son operadas ni controladas por <strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong>, por ello, no se hace responsable de los contenidos de esos sitios Web ni est\u00e1n cubiertas por el presente Aviso Legal. Si accede a estas p\u00e1ginas Webs deber\u00e1 tener en cuenta que sus pol\u00edticas de privacidad pueden ser diferentes a la nuestra.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>LEGISLACI\u00d3N APLICABLE Y COMPETENCIA JURISDICCIONAL<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">El presente Aviso Legal se rige por la normativa espa\u00f1ola vigente que le es de aplicaci\u00f3n.<\/span><br \/>\n<span style=\"color: #000000;\">Para la resoluci\u00f3n de las controversias que pudieran derivarse como consecuencia de lo dispuesto en las presentes disposiciones y sobre su interpretaci\u00f3n, aplicaci\u00f3n y cumplimiento. El usuario, en virtud de la aceptaci\u00f3n de las condiciones recogidas en este Aviso legal, renuncia expresamente a cualquier otro fuero que pudiera corresponderle.<\/span><br \/>\n<span style=\"color: #000000;\">En cualquier caso, dentro de la jurisdicci\u00f3n espa\u00f1ola, si la legislaci\u00f3n permitiese someterse a un fuero en concreto, el usuario renuncia expresamente al fuero que pudiera corresponderle y se somete voluntariamente a la jurisdicci\u00f3n de los Juzgados y Tribunales de PUERTO DEL ROSARIO.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>GRUPO GANADEROS DE FUERTEVENTURA S.L.<\/strong><\/span><br \/>\n<span style=\"color: #000000;\">COCHINILLA URB. RISCO PRIETO, 29 &#8211; Nave PUERTO DEL ROSARIO 35600 (LAS PALMAS)<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aviso Legal y Pol\u00edtica de Privacidad IDENTIFICACI\u00d3N En cumplimiento con el deber de informaci\u00f3n recogido en art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, GRUPO GANADEROS DE FUERTEVENTURA S.L., le informa que los datos aqu\u00ed consignados corresponden a la entidad titular&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1222","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso Legal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxorata.es\/en\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maxorata.es\/en\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Maxorata\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-11T12:11:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/aviso-legal\\\/\",\"name\":\"Aviso Legal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\"},\"datePublished\":\"2016-02-12T14:47:05+00:00\",\"dateModified\":\"2020-12-11T12:11:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maxorata.es\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maxorata.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"name\":\"Maxorata\",\"description\":\"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura\",\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maxorata.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\",\"name\":\"Grupo Ganaderos de Fuerteventura S.L\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"width\":109,\"height\":77,\"caption\":\"Grupo Ganaderos de Fuerteventura S.L\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxorata.es\/en\/aviso-legal\/","og_locale":"en_GB","og_type":"article","og_title":"[:es]Aviso Legal[:] - Maxorata","og_url":"https:\/\/maxorata.es\/en\/aviso-legal\/","og_site_name":"Maxorata","article_modified_time":"2020-12-11T12:11:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maxorata.es\/aviso-legal\/","url":"https:\/\/maxorata.es\/aviso-legal\/","name":"Aviso Legal","isPartOf":{"@id":"https:\/\/maxorata.es\/#website"},"datePublished":"2016-02-12T14:47:05+00:00","dateModified":"2020-12-11T12:11:43+00:00","breadcrumb":{"@id":"https:\/\/maxorata.es\/aviso-legal\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maxorata.es\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maxorata.es\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maxorata.es\/"},{"@type":"ListItem","position":2,"name":"Aviso Legal"}]},{"@type":"WebSite","@id":"https:\/\/maxorata.es\/#website","url":"https:\/\/maxorata.es\/","name":"Maxorata","description":"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura","publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxorata.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maxorata.es\/#organization","name":"Grupo Ganaderos de Fuerteventura S.L","url":"https:\/\/maxorata.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","width":109,"height":77,"caption":"Grupo Ganaderos de Fuerteventura S.L"},"image":{"@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages\/1222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/comments?post=1222"}],"version-history":[{"count":0,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages\/1222\/revisions"}],"wp:attachment":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/media?parent=1222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}