{"id":5860,"date":"2025-01-20T12:43:04","date_gmt":"2025-01-20T12:43:04","guid":{"rendered":"https:\/\/www.maxorata.es\/?page_id=5860"},"modified":"2025-01-27T15:41:56","modified_gmt":"2025-01-27T15:41:56","slug":"yogures-el-tofio","status":"publish","type":"page","link":"https:\/\/maxorata.es\/en\/yogures-el-tofio\/","title":{"rendered":"El Tofio yoghurts"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div class=\"vc_row wpb_row vc_row-fluid dt-default\" style=\"margin-top: 0px;margin-bottom: 0px\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_revslider_element wpb_content_element\">\n\t\t\t<!-- START Yogures Tofio EN REVOLUTION SLIDER 6.7.40 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_26_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_26_1\" style=\"\" data-version=\"6.7.40\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-30\" data-title=\"Slide\" data-anim=\"r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/maxorata.es\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"banner yogures\" title=\"banner_yogures\" width=\"2000\" height=\"557\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/banner_yogures.jpg\" data-bg=\"p:center top;f:contain;\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-26-slide-30-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#4b94ce\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-1px;y:c;yo:21px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:44;l:22;fw:700;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:790;sp:1170;sR:790;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7040;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;font-family:'Lora';\"\n\t\t\t\t\t\t\t>Goat yogurt El Tofio, \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-26-slide-30-layer-6\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#4b94ce\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:356px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:44;l:22;fw:700;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:1330;sp:1170;sR:1330;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"st:w;sR:6500;auto:true;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Lora';\"\n\t\t\t\t\t\t\t>source of health \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-26-slide-30-layer-12\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:57px;\"\n\t\t\t\t\t\t\t\tdata-text=\"l:22;a:inherit;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:303px;h:295px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-100%;o:1;\"\n\t\t\t\t\t\t\t\tdata-frame_0_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"st:70;sp:1570;sR:70;\"\n\t\t\t\t\t\t\t\tdata-frame_1_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:7360;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/maxorata.es\/wp-content\/plugins\/revslider\/sr6\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"435\" height=\"423\" data-lazyload=\"\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/m-eltofio.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_26_1',rl:[1240,1024,778,480],el:[580],gw:[1980],gh:[580],type:'hero',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider261\"]!==undefined) {window.RS_MODULES.modules[\"revslider261\"].once = false;window.revapi26 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_row-no-padding\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"advanced-tabs-desc-wrap-6467\" class=\"ult_tabs tabs-quesos\" style=\" \" data-tabsstyle=\"style1\"\n data-titlebg=\"#e7ecea\" data-titlecolor=\"#74777b\" data-fullheight=\"off\"\n data-titlehoverbg=\"#4f90d1\" data-titlehovercolor=\"#ffffff\"\n data-rotatetabs=\"0\" data-responsivemode=\"Both\" data-animation=\"Fade\"\ndata-activetitle=\"#ffffff\" data-activeicon=\"\" data-activebg=\"#4f90d1\"  data-respmode=\"Tabs\" data-respwidth=\"400\" data-scroll = \"on\" data-activeindex=\"1\"><ul id=advanced-tabs-wrap-2191 class=\"ult_tabmenu style1 \" style=\"\"><li class=\"ult_tab_li  natural prolasa \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#e7ecea;border-color:transparent;border-width:0px;border-style:solid;border-top-left-radius:8px;\">\n\t\t\t\t\t<a href=\"#yogur-natural\" id=\"yogur-natural\" style=\"color:#74777b;;  \" class=\"ult_a \">\n\t\t\t\t\t   <span class=\"ult_tab_main  Both \">\n\t\t\t\t\t    <span class=\"ult_tab_section\">\n\t\t\t\t\t  \t\t<span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult-responsive\" style=\"\">natural<\/span>\n\t\t\t\t\t\t   \t<span class=\"aio-icon none ult_tab_iconright\" style=\"color:#74777b;font-size:15px;\">\n\t\t\t\t\t\t   \t<i class=\"   ult_tab_icon\"  ><\/i>\n\t\t\t\t\t\t   <\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t   <\/span>\n\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li  azucarado prolasa \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#e7ecea;border-color:transparent;border-width:0px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#yogur-azucarado\" id=\"yogur-azucarado\" style=\"color:#74777b;;  \" class=\"ult_a \">\n\t\t\t\t\t   <span class=\"ult_tab_main  Both \">\n\t\t\t\t\t    <span class=\"ult_tab_section\">\n\t\t\t\t\t  \t\t<span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult-responsive\" style=\"\">sweetened<\/span>\n\t\t\t\t\t\t   \t<span class=\"aio-icon none ult_tab_iconright\" style=\"color:#74777b;font-size:15px;\">\n\t\t\t\t\t\t   \t<i class=\"   ult_tab_icon\"  ><\/i>\n\t\t\t\t\t\t   <\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t   <\/span>\n\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li  frutas prolasa \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#e7ecea;border-color:transparent;border-width:0px;border-style:solid;\">\n\t\t\t\t\t<a href=\"#yogur-frutas\" id=\"yogur-frutas\" style=\"color:#74777b;;  \" class=\"ult_a \">\n\t\t\t\t\t   <span class=\"ult_tab_main  Both \">\n\t\t\t\t\t    <span class=\"ult_tab_section\">\n\t\t\t\t\t  \t\t<span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult-responsive\" style=\"\">forest fruits<\/span>\n\t\t\t\t\t\t   \t<span class=\"aio-icon none ult_tab_iconright\" style=\"color:#74777b;font-size:15px;\">\n\t\t\t\t\t\t   \t<i class=\"   ult_tab_icon\"  ><\/i>\n\t\t\t\t\t\t   <\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t   <\/span>\n\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><li class=\"ult_tab_li  higos prolasa \" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\" style=\"background-color:#e7ecea;border-color:transparent;border-width:0px;border-style:solid;border-top-right-radius:8px;\">\n\t\t\t\t\t<a href=\"#yogur-higos\" id=\"yogur-higos\" style=\"color:#74777b;;  \" class=\"ult_a \">\n\t\t\t\t\t   <span class=\"ult_tab_main  Both \">\n\t\t\t\t\t    <span class=\"ult_tab_section\">\n\t\t\t\t\t  \t\t<span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult-responsive\" style=\"\">figs<\/span>\n\t\t\t\t\t\t   \t<span class=\"aio-icon none ult_tab_iconright\" style=\"color:#74777b;font-size:15px;\">\n\t\t\t\t\t\t   \t<i class=\"   ult_tab_icon\"  ><\/i>\n\t\t\t\t\t\t   <\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t   <\/span>\n\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/li><\/ul><div  data-ultimate-target='#advanced-tabs-desc-wrap-6467 .ult_tabcontent .ult_tab_min_contain  p'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' class=\"ult_tabcontent ult-responsive style1\" style=\"color:#74777b;\"><div class=\"ult_tab_min_contain \" >\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element  product-title natural\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Natural goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440178596\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra natural\" title=\"ElTofio_yogur_Natural\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_natural-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071706153\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717299390 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra natural\" title=\"ElTofio_yogur_Natural\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_natural-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element  product-title azucarado\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Sweetened goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440234384\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra natural azucarado\" title=\"ElTofio_yogur_Azucarado\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_azucarado\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071696710\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717312865 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra natural azucarado\" title=\"ElTofio_yogur_Azucarado\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_azucarado\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element  product-title frutas\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Forest fruits goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440252936\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra cremoso con frutas del bosque\" title=\"ElTofio_yogur_Frutosbosque\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_frutosbosque\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071687751\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717325646 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra cremoso con frutas del bosque\" title=\"ElTofio_yogur_Frutosbosque\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_frutosbosque\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<div  class=\"ult_tabitemname\"  >\n\t\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element  product-title higos\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Figs goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440276358\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra cremoso con higos\" title=\"ElTofio_yogur_Higos\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_higos-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071679322\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717338368 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra cremoso con higos\" title=\"ElTofio_yogur_Higos\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_higos-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t<\/div><\/div><\/div><\/div><div class=\"ult_acord advanced-tabs-desc-wrap-6467\">\n   <div class=\"ult-tabto-accordion \" style=\"width:;\"\n    data-titlecolor=\"#74777b\"  data-titlebg=\"#e7ecea\"\n     data-titlehoverbg=\"#4f90d1\" data-titlehovercolor=\"#ffffff\" data-animation=\"Fade\"\n     data-activetitle=\"#ffffff\" data-activeicon=\"\" data-activebg=\"#4f90d1\" data-scroll = \"on\" data-activeindex=\"1\" >\n     <dl><dt class=\"natural prolasa\">\n        \t<a class=\"ult-tabto-actitle withBorder ult_a\" id=\"yogur-natural\" style=\"color:#74777b;;background-color:#e7ecea;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#yogur-natural\">\n        \t\t<i class=\"accordion-icon\"><\/i>\n        \t\t\t<span class=\"ult_tab_main ult_ac_mainBoth\">\n\t\t\t\t\t   <span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult_acordian-text ult-responsive\" style=\";color:inherit \" >natural<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t   <div class=\"aio-icon none \" style=\"color:#74777b;font-size:15px;\" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\">\n\t\t\t\t\t   <i class=\"    ult_tab_icon\"  ><\/i>\n\t\t\t\t\t   <\/div>\n\t\t\t\t\t<\/a><\/dt>\n            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t            <div class=\"ult-tabto-acontent\" style=\"color:#74777b;\">\n\t\t\t               \n\t<div class=\"wpb_text_column wpb_content_element  product-title natural\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Natural goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440178596\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra natural\" title=\"ElTofio_yogur_Natural\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_natural-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071706153\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717299390 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Natural-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra natural\" title=\"ElTofio_yogur_Natural\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_natural-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t            <\/div>\n        \t<\/dd><dt class=\"azucarado prolasa\">\n        \t<a class=\"ult-tabto-actitle withBorder ult_a\" id=\"yogur-azucarado\" style=\"color:#74777b;;background-color:#e7ecea;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#yogur-azucarado\">\n        \t\t<i class=\"accordion-icon\"><\/i>\n        \t\t\t<span class=\"ult_tab_main ult_ac_mainBoth\">\n\t\t\t\t\t   <span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult_acordian-text ult-responsive\" style=\";color:inherit \" >sweetened<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t   <div class=\"aio-icon none \" style=\"color:#74777b;font-size:15px;\" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\">\n\t\t\t\t\t   <i class=\"    ult_tab_icon\"  ><\/i>\n\t\t\t\t\t   <\/div>\n\t\t\t\t\t<\/a><\/dt>\n            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t            <div class=\"ult-tabto-acontent\" style=\"color:#74777b;\">\n\t\t\t               \n\t<div class=\"wpb_text_column wpb_content_element  product-title azucarado\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Sweetened goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440234384\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra natural azucarado\" title=\"ElTofio_yogur_Azucarado\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_azucarado\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071696710\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717312865 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Azucarado-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra natural azucarado\" title=\"ElTofio_yogur_Azucarado\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_azucarado\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t            <\/div>\n        \t<\/dd><dt class=\"frutas prolasa\">\n        \t<a class=\"ult-tabto-actitle withBorder ult_a\" id=\"yogur-frutas\" style=\"color:#74777b;;background-color:#e7ecea;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#yogur-frutas\">\n        \t\t<i class=\"accordion-icon\"><\/i>\n        \t\t\t<span class=\"ult_tab_main ult_ac_mainBoth\">\n\t\t\t\t\t   <span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult_acordian-text ult-responsive\" style=\";color:inherit \" >forest fruits<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t   <div class=\"aio-icon none \" style=\"color:#74777b;font-size:15px;\" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\">\n\t\t\t\t\t   <i class=\"    ult_tab_icon\"  ><\/i>\n\t\t\t\t\t   <\/div>\n\t\t\t\t\t<\/a><\/dt>\n            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t            <div class=\"ult-tabto-acontent\" style=\"color:#74777b;\">\n\t\t\t               \n\t<div class=\"wpb_text_column wpb_content_element  product-title frutas\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Forest fruits goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440252936\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra cremoso con frutas del bosque\" title=\"ElTofio_yogur_Frutosbosque\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_frutosbosque\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071687751\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717325646 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Frutosbosque-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra cremoso con frutas del bosque\" title=\"ElTofio_yogur_Frutosbosque\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_frutosbosque\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t            <\/div>\n        \t<\/dd><dt class=\"higos prolasa\">\n        \t<a class=\"ult-tabto-actitle withBorder ult_a\" id=\"yogur-higos\" style=\"color:#74777b;;background-color:#e7ecea;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;border-bottom-color:transparent;border-bottom-width:0px;border-bottom-style:solid;\" href=\"#yogur-higos\">\n        \t\t<i class=\"accordion-icon\"><\/i>\n        \t\t\t<span class=\"ult_tab_main ult_ac_mainBoth\">\n\t\t\t\t\t   <span  data-ultimate-target='#advanced-tabs-wrap-2191 .ult-span-text'  data-responsive-json-new='{\"font-size\":\"desktop:15px;\",\"line-height\":\"\"}'  class=\"ult-span-text ult_acordian-text ult-responsive\" style=\";color:inherit \" >figs<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t   <div class=\"aio-icon none \" style=\"color:#74777b;font-size:15px;\" data-iconcolor=\"#74777b\" data-iconhover=\"#ffffff\">\n\t\t\t\t\t   <i class=\"    ult_tab_icon\"  ><\/i>\n\t\t\t\t\t   <\/div>\n\t\t\t\t\t<\/a><\/dt>\n            \t\t<dd class=\"ult-tabto-accordionItem ult-tabto-accolapsed\">\n\t\t\t            <div class=\"ult-tabto-acontent\" style=\"color:#74777b;\">\n\t\t\t               \n\t<div class=\"wpb_text_column wpb_content_element  product-title higos\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1 style=\"text-align: center; color: #ffffff; font-weight: 900;\">Figs goat\u2019s milk yoghurt<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid container vc_custom_1551440276358\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"710\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos.png\" class=\"vc_single_image-img attachment-full\" alt=\"El Tofio yogur de cabra cremoso con higos\" title=\"ElTofio_yogur_Higos\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos.png 1000w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos-300x213.png 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos-768x545.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_higos-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left  vc_custom_1682071679322\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/picto_leche_cabra_EN-120x120.png\" width=\"120\" height=\"120\" alt=\"100% canarian goat milk\" title=\"picto_leche_cabra_EN\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/picto_leche_cabra_en\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_left vc_separator_no_text wpb_content_element  wpb_content_element\"   style=\"width: 30%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2><span style=\"color: #000000;\">Characteristics<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory.<\/p>\n<p style=\"font-weight: 400;\">El Tofio yogurts is a healthy way to obtain energy, nutrients and minerals. It is ideal as a nutritious breakfast or snack as it is rich in calcium and protein. In addition, the natural ferments present in the yogurt help break down the lactose, making it ideal for people with problems digesting it.<\/p>\n<p style=\"font-weight: 400;\">Yogurt provides the essential nutrients, calcium and protein that your body needs. Moreover, its high content of vitamin D contributes to the normal functioning of the immune system.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #000000;\"><a class=\"btn btn-black\" style=\"color: #000000;\" href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/05\/Ficha_yogures_ElTofio.pdf\" target=\"_blank\" rel=\"noopener\">DATA SHEET<\/a><\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1554717338368 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_2 vc_sep_pos_align_center vc_separator_no_text wpb_content_element  wpb_content_element container\"   style=\"width: 10%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  container\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\"><span style=\"color: #000000;\">Available formats<\/span><\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper  \"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/04\/ElTofio_yogur_Higos-340x240.png\" width=\"340\" height=\"240\" alt=\"El Tofio yogur de cabra cremoso con higos\" title=\"ElTofio_yogur_Higos\" loading=\"lazy\"  data-dt-location=\"https:\/\/maxorata.es\/en\/eltofio_yogur_higos-2\/\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element \" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">Bipack 125 g<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t\t\t            <\/div>\n        \t<\/dd>\n    \t<\/dl>\n    <!--<div class=\"extraborder\" style=\"background-color:#4f90d1\"><\/div>-->\n<\/div>\n\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>natural sweetened forest fruits figs Natural goat\u2019s milk yoghurt Characteristics &nbsp; El Tofio yogurt is elaborated with the fresh goat milk from the farms of the island of Lanzarote. We collect the milk daily and it undergoes strict quality controls in our internal laboratory. El Tofio yogurts is a healthy way to obtain energy, nutrients&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5860","page","type-page","status-publish","hentry","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Tofio yoghurts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxorata.es\/en\/yogures-el-tofio\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Tofio yoghurts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maxorata.es\/en\/yogures-el-tofio\/\" \/>\n<meta property=\"og:site_name\" content=\"Maxorata\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T15:41:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/yogures-el-tofio\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/yogures-el-tofio\\\/\",\"name\":\"El Tofio yoghurts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\"},\"datePublished\":\"2025-01-20T12:43:04+00:00\",\"dateModified\":\"2025-01-27T15:41:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/yogures-el-tofio\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maxorata.es\\\/yogures-el-tofio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/yogures-el-tofio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maxorata.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yogures El Tofio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"name\":\"Maxorata\",\"description\":\"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura\",\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maxorata.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\",\"name\":\"Grupo Ganaderos de Fuerteventura S.L\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"width\":109,\"height\":77,\"caption\":\"Grupo Ganaderos de Fuerteventura S.L\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Tofio yoghurts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxorata.es\/en\/yogures-el-tofio\/","og_locale":"en_GB","og_type":"article","og_title":"[:es]Yogures El Tofio[:en]El Tofio yoghurts[:] - Maxorata","og_url":"https:\/\/maxorata.es\/en\/yogures-el-tofio\/","og_site_name":"Maxorata","article_modified_time":"2025-01-27T15:41:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maxorata.es\/yogures-el-tofio\/","url":"https:\/\/maxorata.es\/yogures-el-tofio\/","name":"El Tofio yoghurts","isPartOf":{"@id":"https:\/\/maxorata.es\/#website"},"datePublished":"2025-01-20T12:43:04+00:00","dateModified":"2025-01-27T15:41:56+00:00","breadcrumb":{"@id":"https:\/\/maxorata.es\/yogures-el-tofio\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maxorata.es\/yogures-el-tofio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maxorata.es\/yogures-el-tofio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maxorata.es\/"},{"@type":"ListItem","position":2,"name":"Yogures El Tofio"}]},{"@type":"WebSite","@id":"https:\/\/maxorata.es\/#website","url":"https:\/\/maxorata.es\/","name":"Maxorata","description":"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura","publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxorata.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maxorata.es\/#organization","name":"Grupo Ganaderos de Fuerteventura S.L","url":"https:\/\/maxorata.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","width":109,"height":77,"caption":"Grupo Ganaderos de Fuerteventura S.L"},"image":{"@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages\/5860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/comments?post=5860"}],"version-history":[{"count":1,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages\/5860\/revisions"}],"predecessor-version":[{"id":5944,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/pages\/5860\/revisions\/5944"}],"wp:attachment":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/media?parent=5860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}