{"id":4779,"date":"2020-06-08T13:12:06","date_gmt":"2020-06-08T13:12:06","guid":{"rendered":"https:\/\/www.maxorata.es\/?p=4779"},"modified":"2020-06-09T12:32:05","modified_gmt":"2020-06-09T12:32:05","slug":"10-recetas-con-queso-ganadoras-de-nuestro-concurso","status":"publish","type":"post","link":"https:\/\/maxorata.es\/en\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/","title":{"rendered":"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!"},"content":{"rendered":"<div class=\"\" data-block=\"true\" data-editor=\"ftkci\" data-offset-key=\"8gfkl-0-0\">\n<p class=\"_1mf _1mj\" data-offset-key=\"8gfkl-0-0\">Durante varias semanas de mayo, fuimos recibiendo recetas y -hay que reconocerlo- cada d\u00eda se iban superando. Queremos pensar que, adem\u00e1s del premio en s\u00ed, este juego pudo ser un aliciente m\u00e1s para este tiempo en que est\u00e1bamos confinados en nuestras casas.<\/p>\n<p class=\"_1mf _1mj\" data-offset-key=\"8gfkl-0-0\">Al final, lo m\u00e1s dif\u00edcil, como se suele decir en estos casos, fue decidirse por las recetas ganadoras, pero estamos seguros de que cualquiera de las 10 son recetas con queso muy sabrosas, al igual que muchas que no consiguieron premio. A todos, muchas gracias por participar.<\/p>\n<\/div>\n<h2 data-offset-key=\"8gfkl-0-0\">Las recetas con queso del jurado<\/h2>\n<p data-offset-key=\"8gfkl-0-0\">Tal y como se especificaba en las bases, 3 de las 10 recetas ganadoras las elegir\u00eda el jurado de Grupo Ganaderos de Fuerteventura, directamente: un entrante, un plato principal y un postre. Las otras 7 se elegir\u00edan entre las 30 m\u00e1s votadas.<\/p>\n<h3 data-offset-key=\"8gfkl-0-0\">Tres recetas por elecci\u00f3n directa<\/h3>\n<p data-offset-key=\"8gfkl-0-0\">Los criterios ten\u00edan que ver con la composici\u00f3n, la elaboraci\u00f3n, la originalidad y la presentaci\u00f3n, principalmente. De esta forma, las 3 primeras recetas elegidas fueron:<\/p>\n<ul>\n<li data-offset-key=\"8gfkl-0-0\">Entrante: Ensalada de pulpo y <a href=\"https:\/\/maxorata.es\/el-tofio\/\" target=\"_blank\" rel=\"noopener noreferrer\">queso fresco El Tofio<\/a> en tulipa con salsa de mango, elaborada por <strong>Virginia Monteverde<\/strong>, de Tenerife.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Principal: Solomillo con arroz cremoso de El Tofio ahumado, setas varias, esp\u00e1rragos trigueros, trufa y jam\u00f3n crujiente de bellota. Esta receta de <strong>Oliver Brun<\/strong> (Gran Canaria) fue la \u00fanica votada por los 5 miembros del jurado.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Bombones de <a href=\"https:\/\/maxorata.es\/maxorata\/\" target=\"_blank\" rel=\"noopener noreferrer\">queso Maxorata<\/a> semicurado, que la propuso <strong>Marisol Cabrera<\/strong>, de Puerto del Rosario, cerquita de nuestra casa.<\/li>\n<\/ul>\n<h3 data-offset-key=\"8gfkl-0-0\">Las otras 7 recetas<\/h3>\n<p data-offset-key=\"8gfkl-0-0\">El resto de ganadores, los eleg\u00eda tambi\u00e9n el jurado, pero entre las 30 recetas m\u00e1s votadas por los usuarios. Estas recetas, junto a las otras tres, abrir\u00e1n una nueva secci\u00f3n con recetas de los seguidores de nuestra web. La idea es contar con un espacio que complemente las recetas de nuestros chefs con las de todos aquellos amantes de nuestros quesos.<\/p>\n<ul>\n<li data-offset-key=\"8gfkl-0-0\">Bombones de queso, por Marisol Cabrera<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Timbal de tomate y queso, por Miguel B\u00e1ez Guti\u00e9rrez.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Crep\u00fasculo de mi tierra, por Milagrosa Hern\u00e1ndez Delgado.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Pasta rellena de queso y manzana, por Daida Bethencourt Garcia.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Tarta salada de queso Maxorata, cebolla caramelizada y nueces, por Desir\u00e9e Darias Mart\u00edn.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Solomillo de cerdo en salsa de queso, por Claudia Dugarte.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Flan de queso, por Mar\u00eda Bel\u00e9n Mar\u00edn.<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Flan de queso, por Delia Garc\u00eda Reyes.<\/li>\n<\/ul>\n<p data-offset-key=\"8gfkl-0-0\">Ya hemos empezado a compartirlas en las redes sociales y muy pronto estar\u00e1n tambi\u00e9n en esta web, explicando los ingredientes y los pasos para elaborarlos.<\/p>\n<p data-offset-key=\"8gfkl-0-0\">\n<h3 data-offset-key=\"8gfkl-0-0\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4781 size-large\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera-1024x497.jpg\" alt=\"\" width=\"1024\" height=\"497\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera-1024x497.jpg 1024w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera-300x146.jpg 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera-768x373.jpg 768w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera-150x73.jpg 150w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera-600x292.jpg 600w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-marisol-cabrera.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/h3>\n<h3 data-offset-key=\"8gfkl-0-0\">Los premios<\/h3>\n<p>Los 10 ganadores recibir\u00e1n muy pronto en sus casas 4 kg del queso que ellos eligieron de entre los 10 que se ofrec\u00edan:<\/p>\n<ul>\n<li data-offset-key=\"8gfkl-0-0\">Maxorata tierno<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Maxorata semicurado Piment\u00f3n<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Maxorata semicurado natural<\/li>\n<li data-offset-key=\"8gfkl-0-0\">El Tofio semicurado Piment\u00f3n<\/li>\n<li data-offset-key=\"8gfkl-0-0\">El Tofio semicurado gofio<\/li>\n<li data-offset-key=\"8gfkl-0-0\">El Tofio Tierno ahumado<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Selectum semicurado Piment\u00f3n<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Selectum curado Piment\u00f3n<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Tobar del Oso semicurado<\/li>\n<li data-offset-key=\"8gfkl-0-0\">Tobar del Oso curado<\/li>\n<\/ul>\n<h3 data-offset-key=\"8gfkl-0-0\">El jurado de Grupo Ganaderos de Fuerteventura<\/h3>\n<p data-offset-key=\"8gfkl-0-0\">El jurado estuvo compuesto por 5 miembros del equipo de la empresa. Fue a ellos a quienes toc\u00f3 la tarea de elegir<\/p>\n<div data-offset-key=\"8gfkl-0-0\">\n<div class=\"\"><b class=\"\">\u00c1ngel Gonz\u00e1lez Brito<\/b> Director Comercial<\/div>\n<div class=\"\"><b class=\"\">Nadia Herrera<\/b> Export Manager<\/div>\n<div class=\"\"><b class=\"\">Mayka Jim\u00e9nez Le\u00f3n<\/b> Recursos Humanos<\/div>\n<div class=\"\"><b class=\"\">Marta Hern\u00e1ndez Balaguera<\/b> Directora de f\u00e1brica<\/div>\n<div class=\"\"><b class=\"\">Silvia Ruiz<\/b> T\u00e9cnico de Calidad y Medioambiente<\/div>\n<p>Te las iremos presentando una a una aqu\u00ed, en las redes sociales. Al final, las subiremos todas a la web con los ingredientes y la elaboraci\u00f3n. Muchas gracias a todos por participar y felicidades a los premiados.<\/p>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ftkci\" data-offset-key=\"bgcor-0-0\"><\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"ftkci\" data-offset-key=\"7t305-0-0\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4785 size-large\" src=\"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia-1024x672.jpg\" alt=\"\" width=\"1024\" height=\"672\" srcset=\"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia-1024x672.jpg 1024w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia-300x197.jpg 300w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia-768x504.jpg 768w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia-150x99.jpg 150w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia-600x394.jpg 600w, https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/recetas-maxorata-por-virginia.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante varias semanas de mayo, fuimos recibiendo recetas y -hay que reconocerlo- cada d\u00eda se iban superando. Queremos pensar que, adem\u00e1s del premio en s\u00ed, este juego pudo ser un aliciente m\u00e1s para este tiempo en que est\u00e1bamos confinados en nuestras casas. Al final, lo m\u00e1s dif\u00edcil, como se suele decir en estos casos, fue&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[158],"class_list":["post-4779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sorteos","tag-sorteos","category-160","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxorata.es\/en\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!\" \/>\n<meta property=\"og:description\" content=\"Durante varias semanas de mayo, fuimos recibiendo recetas y -hay que reconocerlo- cada d\u00eda se iban superando. Queremos pensar que, adem\u00e1s del premio en s\u00ed, este juego pudo ser un aliciente m\u00e1s para este tiempo en que est\u00e1bamos confinados en nuestras casas. Al final, lo m\u00e1s dif\u00edcil, como se suele decir en estos casos, fue&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maxorata.es\/en\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/\" \/>\n<meta property=\"og:site_name\" content=\"Maxorata\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T13:12:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T12:32:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1657\" \/>\n\t<meta property=\"og:image:height\" content=\"981\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!\",\"datePublished\":\"2020-06-08T13:12:06+00:00\",\"dateModified\":\"2020-06-09T12:32:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/\"},\"wordCount\":600,\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg\",\"keywords\":[\"Sorteos\"],\"articleSection\":[\"Sorteos\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/\",\"name\":\"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg\",\"datePublished\":\"2020-06-08T13:12:06+00:00\",\"dateModified\":\"2020-06-09T12:32:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg\",\"width\":1657,\"height\":981,\"caption\":\"concurso recetas con queso maxorata oliver brun solomillo 4\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maxorata.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"name\":\"Maxorata\",\"description\":\"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura\",\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maxorata.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\",\"name\":\"Grupo Ganaderos de Fuerteventura S.L\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"width\":109,\"height\":77,\"caption\":\"Grupo Ganaderos de Fuerteventura S.L\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/maxorata.es\\\/en\\\/blog\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxorata.es\/en\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/","og_locale":"en_GB","og_type":"article","og_title":"[:es]\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso![:] - Maxorata","og_description":"Durante varias semanas de mayo, fuimos recibiendo recetas y -hay que reconocerlo- cada d\u00eda se iban superando. Queremos pensar que, adem\u00e1s del premio en s\u00ed, este juego pudo ser un aliciente m\u00e1s para este tiempo en que est\u00e1bamos confinados en nuestras casas. Al final, lo m\u00e1s dif\u00edcil, como se suele decir en estos casos, fue&hellip;","og_url":"https:\/\/maxorata.es\/en\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/","og_site_name":"Maxorata","article_published_time":"2020-06-08T13:12:06+00:00","article_modified_time":"2020-06-09T12:32:05+00:00","og_image":[{"width":1657,"height":981,"url":"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#article","isPartOf":{"@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/"},"author":{"name":"","@id":""},"headline":"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!","datePublished":"2020-06-08T13:12:06+00:00","dateModified":"2020-06-09T12:32:05+00:00","mainEntityOfPage":{"@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/"},"wordCount":600,"publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"image":{"@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#primaryimage"},"thumbnailUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg","keywords":["Sorteos"],"articleSection":["Sorteos"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/","url":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/","name":"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!","isPartOf":{"@id":"https:\/\/maxorata.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#primaryimage"},"image":{"@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#primaryimage"},"thumbnailUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg","datePublished":"2020-06-08T13:12:06+00:00","dateModified":"2020-06-09T12:32:05+00:00","breadcrumb":{"@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#primaryimage","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2020\/06\/concurso-recetas-con-queso-maxorata-oliver-brun-solomillo-4.jpeg","width":1657,"height":981,"caption":"concurso recetas con queso maxorata oliver brun solomillo 4"},{"@type":"BreadcrumbList","@id":"https:\/\/maxorata.es\/blog\/10-recetas-con-queso-ganadoras-de-nuestro-concurso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maxorata.es\/"},{"@type":"ListItem","position":2,"name":"\u00a1Ya tenemos las 10 recetas con queso ganadoras de nuestro concurso!"}]},{"@type":"WebSite","@id":"https:\/\/maxorata.es\/#website","url":"https:\/\/maxorata.es\/","name":"Maxorata","description":"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura","publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxorata.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maxorata.es\/#organization","name":"Grupo Ganaderos de Fuerteventura S.L","url":"https:\/\/maxorata.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","width":109,"height":77,"caption":"Grupo Ganaderos de Fuerteventura S.L"},"image":{"@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/maxorata.es\/en\/blog\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts\/4779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/comments?post=4779"}],"version-history":[{"count":0,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts\/4779\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/media\/4780"}],"wp:attachment":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/media?parent=4779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/categories?post=4779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/tags?post=4779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}