{"id":5532,"date":"2023-09-14T15:50:06","date_gmt":"2023-09-14T14:50:06","guid":{"rendered":"https:\/\/www.maxorata.es\/?p=5532"},"modified":"2023-11-09T14:29:07","modified_gmt":"2023-11-09T14:29:07","slug":"maxorata-mejor-queso-madurado-de-cabra-espana-2023","status":"publish","type":"post","link":"https:\/\/maxorata.es\/en\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/","title":{"rendered":"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023"},"content":{"rendered":"<p style=\"text-align: justify;\">El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d, dentro de la categor\u00eda \u201cAlimentos de Espa\u00f1a Mejores Quesos\u201d.<\/p>\n<p style=\"text-align: justify;\">Nuestro queso Maxorata Curado con Piment\u00f3n con Denominaci\u00f3n de Origen Protegida Queso Majorero, ha sido el \u00fanico producto de Canarias reconocido por el Ministerio de Agricultura, Pesca y Alimentaci\u00f3n con el Premio Alimentos de Espa\u00f1a 2023, incluyendo las categor\u00edas de Mejor Bebida Espirituosa, los Mejores Quesos y los Mejores Vinos. De esta manera, <a href=\"https:\/\/www.canarias7.es\/canarias\/fuerteventura\/queso-maxorata-premio-alimentos-espana-2023-20230803133113-nt.html\" target=\"_blank\" rel=\"noopener\"><strong>Maxorata se convierte en el mejor queso de Espa\u00f1a<\/strong><\/a> en la modalidad &#8220;queso madurado de cabra&#8221;.<\/p>\n<p style=\"text-align: justify;\">Estos premios, cuya resoluci\u00f3n se publica en el Bolet\u00edn Oficial del Estado, tienen como objetivo promocionar, dar a conocer los quesos aut\u00f3ctonos espa\u00f1oles y poner en valor el producto nacional, adem\u00e1s de <a href=\"https:\/\/maxorata.es\/mision-vision-y-valores\/\">reconocer nuestro esfuerzo comercializador<\/a>, innovador, de desarrollo rural y cuidado del medio ambiente, y en la elaboraci\u00f3n de <a href=\"https:\/\/maxorata.es\/filosofia\/\">alimentos de calidad<\/a>.<\/p>\n<p style=\"text-align: justify;\">Este galard\u00f3n se suma a numerosos reconocimientos obtenidos en a\u00f1os anteriores. El a\u00f1o pasado, nuestro Maxorata Curado al Piment\u00f3n obtuvo una medalla <a href=\"https:\/\/maxorata.es\/blog\/queso-maxorata-triunfa-en-el-mundial-do-queijo-do-brasil-2022\/#:~:text=Todos%20los%20quesos%20espa%C3%B1oles%20obtuvieron,un%20total%20de%2035%20quesos.\">SuperOro en el Mundial do Queijo do Brasil 2022<\/a>, mientras que el Maxorata Semicurado Piment\u00f3n fue elegido el Mejor Queso de Canarias 2022 en el cert\u00e1men Agrocanarias 2022. Por otra parte, el Tofio Curado al Piment\u00f3n y el <a href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_ElTofio_1122.pdf\">Tofio Semicurado con Gofio<\/a> consiguieron sendas medallas de Oro en la World Cheese Awards 2022<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, en 2021 nuestro Selectum Curado Piment\u00f3n tambi\u00e9n logr\u00f3 la <a href=\"https:\/\/maxorata.es\/blog\/selectum-curado-pimenton-super-oro-world-cheese-awards-2021\/\">Super Oro en los World Cheese Awards 2021<\/a> y ese mismo a\u00f1o el queso Maxorata Piment\u00f3n Curado fue elegido <a href=\"https:\/\/maxorata.es\/blog\/mejor-queso-de-cabra-curado-de-espana-maxorata-curado-pimenton\/\">mejor queso de cabra curado de Espa\u00f1a en el Campeonato GourmetQuesos<\/a><\/p>\n<p style=\"text-align: justify;\">Puedes consultar la lista completa de premios de nuestros quesos en los siguientes links:<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_Maxorata_1122.pdf\">https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_Maxorata_1122.pdf<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_ElTofio_1122.pdf\">https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_ElTofio_1122.pdf<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_Selectum_1122.pdf\">https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_Selectum_1122.pdf<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_TobardelOso_1122.pdf\">https:\/\/maxorata.es\/wp-content\/uploads\/2023\/01\/Premios_TobardelOso_1122.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d, dentro de la categor\u00eda \u201cAlimentos de Espa\u00f1a Mejores Quesos\u201d. Nuestro queso Maxorata Curado con Piment\u00f3n con Denominaci\u00f3n de Origen Protegida Queso Majorero, ha sido el \u00fanico producto de Canarias reconocido por el Ministerio de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42,41,167],"tags":[230,235,234,229,232,236,231,157,227,228,233],"class_list":["post-5532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-premios","category-eventos","tag-cabra-majorera","tag-canarias","tag-espana","tag-fuerteventura","tag-grupo-ganaderos-fuerteventura","tag-islas-canarias","tag-maxorata-curado-con-pimenton","tag-maxorata-curado","tag-maxorata-madurado","tag-mejor-queso-de-cabra-madurado-2023","tag-ministerio-de-agricultura","category-42","category-41","category-167","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023<\/title>\n<meta name=\"description\" content=\"El Ministerio de Agricultura nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxorata.es\/en\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Agricultura nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maxorata.es\/en\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Maxorata\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T14:50:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T14:29:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/09\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"922\" \/>\n\t<meta property=\"og:image:height\" content=\"922\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023\",\"datePublished\":\"2023-09-14T14:50:06+00:00\",\"dateModified\":\"2023-11-09T14:29:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/\"},\"wordCount\":345,\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg\",\"keywords\":[\"Cabra majorera\",\"Canarias\",\"Espa\u00f1a\",\"Fuerteventura\",\"Grupo Ganaderos fuerteventura\",\"Islas Canarias.\",\"Maxorata curado con piment\u00f3n\",\"Maxorata Curado\",\"Maxorata madurado\",\"Mejor queso de cabra madurado 2023\",\"Ministerio de Agricultura\"],\"articleSection\":[\"Noticias\",\"Premios\",\"Eventos\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/\",\"name\":\"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg\",\"datePublished\":\"2023-09-14T14:50:06+00:00\",\"dateModified\":\"2023-11-09T14:29:07+00:00\",\"description\":\"El Ministerio de Agricultura nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg\",\"width\":922,\"height\":922},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maxorata.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"name\":\"Maxorata\",\"description\":\"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura\",\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maxorata.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\",\"name\":\"Grupo Ganaderos de Fuerteventura S.L\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"width\":109,\"height\":77,\"caption\":\"Grupo Ganaderos de Fuerteventura S.L\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/maxorata.es\\\/en\\\/blog\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023","description":"El Ministerio de Agricultura nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxorata.es\/en\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/","og_locale":"en_GB","og_type":"article","og_title":"[:es]Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023[:] - Maxorata","og_description":"El Ministerio de Agricultura nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d.","og_url":"https:\/\/maxorata.es\/en\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/","og_site_name":"Maxorata","article_published_time":"2023-09-14T14:50:06+00:00","article_modified_time":"2023-11-09T14:29:07+00:00","og_image":[{"width":922,"height":922,"url":"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/09\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#article","isPartOf":{"@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/"},"author":{"name":"","@id":""},"headline":"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023","datePublished":"2023-09-14T14:50:06+00:00","dateModified":"2023-11-09T14:29:07+00:00","mainEntityOfPage":{"@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/"},"wordCount":345,"publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"image":{"@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/09\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg","keywords":["Cabra majorera","Canarias","Espa\u00f1a","Fuerteventura","Grupo Ganaderos fuerteventura","Islas Canarias.","Maxorata curado con piment\u00f3n","Maxorata Curado","Maxorata madurado","Mejor queso de cabra madurado 2023","Ministerio de Agricultura"],"articleSection":["Noticias","Premios","Eventos"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/","url":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/","name":"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023","isPartOf":{"@id":"https:\/\/maxorata.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#primaryimage"},"image":{"@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/09\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg","datePublished":"2023-09-14T14:50:06+00:00","dateModified":"2023-11-09T14:29:07+00:00","description":"El Ministerio de Agricultura nos ha galardonado con el primer premio en la modalidad \u201cqueso madurado de cabra\u201d.","breadcrumb":{"@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#primaryimage","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/09\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2023\/09\/Maxorata-mejor-queso-madurado-de-cabra-espana.jpg","width":922,"height":922},{"@type":"BreadcrumbList","@id":"https:\/\/maxorata.es\/blog\/maxorata-mejor-queso-madurado-de-cabra-espana-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maxorata.es\/"},{"@type":"ListItem","position":2,"name":"Maxorata, mejor queso madurado de cabra de Espa\u00f1a 2023"}]},{"@type":"WebSite","@id":"https:\/\/maxorata.es\/#website","url":"https:\/\/maxorata.es\/","name":"Maxorata","description":"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura","publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxorata.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maxorata.es\/#organization","name":"Grupo Ganaderos de Fuerteventura S.L","url":"https:\/\/maxorata.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","width":109,"height":77,"caption":"Grupo Ganaderos de Fuerteventura S.L"},"image":{"@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/maxorata.es\/en\/blog\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts\/5532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/comments?post=5532"}],"version-history":[{"count":0,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts\/5532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/media\/5574"}],"wp:attachment":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/media?parent=5532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/categories?post=5532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/tags?post=5532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}