{"id":196,"count":1,"description":"","link":"https:\/\/maxorata.es\/en\/blog\/tag\/postres-ale-de-la-nuez\/","name":"Postres Ale de la Nuez","slug":"postres-ale-de-la-nuez","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Postres Ale de la Nuez archivos - Maxorata<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxorata.es\/en\/blog\/tag\/postres-ale-de-la-nuez\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:locale:alternate\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Postres Ale de la Nuez archivos - Maxorata\" \/>\n<meta property=\"og:site_name\" content=\"Maxorata\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/tag\\\/postres-ale-de-la-nuez\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/tag\\\/postres-ale-de-la-nuez\\\/\",\"name\":\"Postres Ale de la Nuez archivos - Maxorata\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/tag\\\/postres-ale-de-la-nuez\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/blog\\\/tag\\\/postres-ale-de-la-nuez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/maxorata.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Postres Ale de la Nuez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#website\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"name\":\"Maxorata\",\"description\":\"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura\",\"publisher\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maxorata.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#organization\",\"name\":\"Grupo Ganaderos de Fuerteventura S.L\",\"url\":\"https:\\\/\\\/maxorata.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/maxorata.es\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo.jpg\",\"width\":109,\"height\":77,\"caption\":\"Grupo Ganaderos de Fuerteventura S.L\"},\"image\":{\"@id\":\"https:\\\/\\\/maxorata.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Postres Ale de la Nuez archivos - Maxorata","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxorata.es\/en\/blog\/tag\/postres-ale-de-la-nuez\/","og_locale":"en_GB","og_type":"article","og_title":"Postres Ale de la Nuez archivos - Maxorata","og_site_name":"Maxorata","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/maxorata.es\/blog\/tag\/postres-ale-de-la-nuez\/","url":"https:\/\/maxorata.es\/blog\/tag\/postres-ale-de-la-nuez\/","name":"Postres Ale de la Nuez archivos - Maxorata","isPartOf":{"@id":"https:\/\/maxorata.es\/#website"},"breadcrumb":{"@id":"https:\/\/maxorata.es\/blog\/tag\/postres-ale-de-la-nuez\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/maxorata.es\/blog\/tag\/postres-ale-de-la-nuez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/maxorata.es\/"},{"@type":"ListItem","position":2,"name":"Postres Ale de la Nuez"}]},{"@type":"WebSite","@id":"https:\/\/maxorata.es\/#website","url":"https:\/\/maxorata.es\/","name":"Maxorata","description":"Queso majorero y otros productos l\u00e1cteos del Grupo Ganaderos de Fuerteventura","publisher":{"@id":"https:\/\/maxorata.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxorata.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/maxorata.es\/#organization","name":"Grupo Ganaderos de Fuerteventura S.L","url":"https:\/\/maxorata.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/","url":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","contentUrl":"https:\/\/maxorata.es\/wp-content\/uploads\/2018\/05\/logo.jpg","width":109,"height":77,"caption":"Grupo Ganaderos de Fuerteventura S.L"},"image":{"@id":"https:\/\/maxorata.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/tags\/196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/maxorata.es\/en\/wp-json\/wp\/v2\/posts?tags=196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}